{"id":1270,"date":"2024-09-27T16:42:32","date_gmt":"2024-09-27T16:42:32","guid":{"rendered":"https:\/\/canpasrecinzioni.it\/produits\/"},"modified":"2024-09-27T16:42:34","modified_gmt":"2024-09-27T16:42:34","slug":"produits","status":"publish","type":"page","link":"https:\/\/canpasrecinzioni.it\/fr\/produits\/","title":{"rendered":"Produits"},"content":{"rendered":"<p>[vc_row css_animation=\u00a0\u00bb\u00a0\u00bb row_type=\u00a0\u00bbrow\u00a0\u00bb use_row_as_full_screen_section=\u00a0\u00bbno\u00a0\u00bb type=\u00a0\u00bbfull_width\u00a0\u00bb angled_section=\u00a0\u00bbno\u00a0\u00bb text_align=\u00a0\u00bbcenter\u00a0\u00bb background_image_as_pattern=\u00a0\u00bbwithout_pattern\u00a0\u00bb z_index=\u00a0\u00bb\u00a0\u00bb][vc_column][vc_column_text]Le <strong>caillebotis \u00e9lectrosoud\u00e9<\/strong> est d\u00e9fini comme une structure en treillis compos\u00e9e de barres porteuses reli\u00e9es orthogonalement \u00e0 des barres transversales.<br \/>\nLes points de connexion entre les deux types de barres du <strong>caillebotis \u00e9lectrosoud\u00e9<\/strong> sont appel\u00e9s \u00ab\u00a0n\u0153uds\u00a0\u00bb.<br \/>\nLa liaison des barres porteuses aux barres transversales est obtenue par l&rsquo;action combin\u00e9e de l&rsquo;\u00e9lectrosoudage &#8211; sans apport de mati\u00e8re &#8211; et de la pression, concentr\u00e9e sur tous les n\u0153uds.<br \/>\nCe processus aboutit \u00e0 l&rsquo;interp\u00e9n\u00e9tration des barres transversales dans les barres portantes.<br \/>\nIl est facile de comprendre que la structure ainsi form\u00e9e offre une charge de travail \u00e9lev\u00e9e (charge support\u00e9e \/ poids propre) avec une grande perm\u00e9abilit\u00e9 \u00e0 la lumi\u00e8re et \u00e0 l&rsquo;air.<br \/>\nCes caract\u00e9ristiques lui permettent d&rsquo;\u00eatre <strong>largement utilis\u00e9 dans les installations industrielles et les constructions civiles pour les passerelles, les paliers et les marches.<\/strong> Leur<strong>haute r\u00e9sistance<\/strong> leur permet d&rsquo;\u00eatre utilis\u00e9s comme <strong>rev\u00eatement de sol dans les installations industrielles, les centrales \u00e9lectriques, etc.<\/strong> Tous les caillebotis fournis par <strong>CANPAS<\/strong> srl sont fabriqu\u00e9s en acier S 235 Jr selon la norme UNI EN ISO 10025, galvanis\u00e9 \u00e0 chaud selon la norme UNI EN ISO 1461.[\/vc_column_text][vc_column_text]<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row row_type=\u00a0\u00bbparallax\u00a0\u00bb parallax_content_width=\u00a0\u00bbin_grid\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb full_screen_section_height=\u00a0\u00bbno\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1689175402651{background-color: #ffffff !important;}\u00a0\u00bb][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_empty_space][vc_single_image image=\u00a0\u00bb730&Prime; img_size=\u00a0\u00bblarge\u00a0\u00bb onclick=\u00a0\u00bbcustom_link\u00a0\u00bb qode_css_animation=\u00a0\u00bb\u00a0\u00bb link=\u00a0\u00bbhttps:\/\/canpasrecinzioni.it\/gradini\/\u00a0\u00bb][vc_empty_space][vc_column_text]<\/p>\n<h3 class=\"portfolio-item-title\"><a href=\"https:\/\/canpasrecinzioni.it\/gradini\/\">\u00c9tapes<\/a><\/h3>\n<p>  Les marches en caillebotis \u00e9lectrosoud\u00e9 sont utilis\u00e9es dans les escaliers ext\u00e9rieurs et les escaliers de secours en raison de leurs caract\u00e9ristiques portantes favorables et de leur grande perm\u00e9abilit\u00e9 \u00e0 la lumi\u00e8re et \u00e0 l&rsquo;air.<br \/>\nLes marches en caillebotis soud\u00e9 de CANPAS sont disponibles en diff\u00e9rentes dimensions pour r\u00e9pondre \u00e0 toutes les exigences.[\/vc_column_text][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_empty_space][vc_single_image image=\u00a0\u00bb533&Prime; img_size=\u00a0\u00bblarge\u00a0\u00bb onclick=\u00a0\u00bbcustom_link\u00a0\u00bb qode_css_animation=\u00a0\u00bb\u00a0\u00bb link=\u00a0\u00bbhttps:\/\/canpasrecinzioni.it\/griglie\/\u00a0\u00bb][vc_empty_space][vc_column_text]<\/p>\n<h3 class=\"portfolio-item-title\"><a href=\"https:\/\/canpasrecinzioni.it\/griglie\/\">Grilles<\/a><\/h3>\n<p>  Gr\u00e2ce \u00e0 leurs caract\u00e9ristiques d&rsquo;\u00e9coulement favorables et \u00e0 leur grande perm\u00e9abilit\u00e9 \u00e0 la lumi\u00e8re et \u00e0 l&rsquo;air, les caillebotis soud\u00e9s sont tr\u00e8s polyvalents et peuvent \u00eatre utilis\u00e9s aussi bien dans des applications r\u00e9sidentielles qu&rsquo;industrielles.[\/vc_column_text][\/vc_column][\/vc_row][vc_row row_type=\u00a0\u00bbparallax\u00a0\u00bb parallax_content_width=\u00a0\u00bbin_grid\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb full_screen_section_height=\u00a0\u00bbno\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1689175402651{background-color: #ffffff !important;}\u00a0\u00bb][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_empty_space][vc_single_image image=\u00a0\u00bb534&Prime; img_size=\u00a0\u00bblarge\u00a0\u00bb onclick=\u00a0\u00bbcustom_link\u00a0\u00bb qode_css_animation=\u00a0\u00bb\u00a0\u00bb link=\u00a0\u00bbhttps:\/\/canpasrecinzioni.it\/grate\/\u00a0\u00bb][vc_empty_space][vc_column_text]<\/p>\n<h3 class=\"portfolio-item-title\"><a href=\"https:\/\/canpasrecinzioni.it\/griglie\/\">Grille<\/a><\/h3>\n<p>  Les caillebotis disponibles en longueurs de 6,1 m x 1 m sont fabriqu\u00e9s en caillebotis \u00e9lectrosoud\u00e9.<br \/>\nGr\u00e2ce \u00e0 leurs caract\u00e9ristiques d&rsquo;\u00e9coulement favorables combin\u00e9es \u00e0 leur haute perm\u00e9abilit\u00e9 \u00e0 la lumi\u00e8re et \u00e0 l&rsquo;air, nos caillebotis sont tr\u00e8s polyvalents et peuvent \u00eatre utilis\u00e9s aussi bien dans des applications r\u00e9sidentielles qu&rsquo;industrielles.<br \/>\nChez CANPAS, vous trouverez une large gamme de grilles et de plaques pour r\u00e9pondre \u00e0 toutes les exigences.[\/vc_column_text][vc_empty_space][\/vc_column][vc_column width=\u00a0\u00bb1\/2&Prime;][vc_empty_space][vc_single_image image=\u00a0\u00bb535&Prime; img_size=\u00a0\u00bblarge\u00a0\u00bb onclick=\u00a0\u00bbcustom_link\u00a0\u00bb qode_css_animation=\u00a0\u00bb\u00a0\u00bb link=\u00a0\u00bbhttps:\/\/canpasrecinzioni.it\/fr\/accessoires\/\u00a0\u00bb][vc_empty_space][vc_column_text]<\/p>\n<h3 class=\"portfolio-item-title\"><a href=\"https:\/\/canpasrecinzioni.it\/fr\/accessoires\/\">Accessoires<\/a><\/h3>\n<p>  Pour compl\u00e9ter et satisfaire tous les besoins, nous disposons d&rsquo;accessoires sp\u00e9cifiques pour tous les types de caillebotis.[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row css_animation=\u00a0\u00bb\u00a0\u00bb row_type=\u00a0\u00bbrow\u00a0\u00bb use_row_as_full_screen_section=\u00a0\u00bbno\u00a0\u00bb type=\u00a0\u00bbfull_width\u00a0\u00bb angled_section=\u00a0\u00bbno\u00a0\u00bb text_align=\u00a0\u00bbcenter\u00a0\u00bb background_image_as_pattern=\u00a0\u00bbwithout_pattern\u00a0\u00bb z_index=\u00a0\u00bb\u00a0\u00bb][vc_column][vc_column_text]Le caillebotis \u00e9lectrosoud\u00e9 est d\u00e9fini comme une structure en treillis compos\u00e9e de barres porteuses reli\u00e9es orthogonalement \u00e0 des barres transversales. Les points de connexion entre les deux types de barres du caillebotis \u00e9lectrosoud\u00e9 sont appel\u00e9s \u00ab\u00a0n\u0153uds\u00a0\u00bb. La&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1270","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/canpasrecinzioni.it\/fr\/wp-json\/wp\/v2\/pages\/1270"}],"collection":[{"href":"https:\/\/canpasrecinzioni.it\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/canpasrecinzioni.it\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/canpasrecinzioni.it\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/canpasrecinzioni.it\/fr\/wp-json\/wp\/v2\/comments?post=1270"}],"version-history":[{"count":1,"href":"https:\/\/canpasrecinzioni.it\/fr\/wp-json\/wp\/v2\/pages\/1270\/revisions"}],"predecessor-version":[{"id":1284,"href":"https:\/\/canpasrecinzioni.it\/fr\/wp-json\/wp\/v2\/pages\/1270\/revisions\/1284"}],"wp:attachment":[{"href":"https:\/\/canpasrecinzioni.it\/fr\/wp-json\/wp\/v2\/media?parent=1270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}